{"id":33695,"date":"2025-05-16T14:59:42","date_gmt":"2025-05-16T12:59:42","guid":{"rendered":"https:\/\/artmotiers.ch\/?page_id=33695"},"modified":"2026-01-04T11:06:02","modified_gmt":"2026-01-04T10:06:02","slug":"exhibitions-2015","status":"publish","type":"page","link":"https:\/\/artmotiers.ch\/en\/retrospective\/exhibitions-2015\/","title":{"rendered":"Exhibitions 2015"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":33591,"parent":33440,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"folder":[],"class_list":["post-33695","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Exhibitions 2015 &#8211; Art M\u00f4tiers<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/artmotiers.ch\/en\/retrospective\/exhibitions-2015\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exhibitions 2015 &#8211; Art M\u00f4tiers\" \/>\n<meta property=\"og:url\" content=\"https:\/\/artmotiers.ch\/en\/retrospective\/exhibitions-2015\/\" \/>\n<meta property=\"og:site_name\" content=\"Art M\u00f4tiers\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-04T10:06:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/artmotiers.ch\/wp-content\/uploads\/2025\/05\/motiersart_affiche_2015-scaled-e1748877053912.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1843\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/artmotiers.ch\\\/en\\\/retrospective\\\/exhibitions-2015\\\/\",\"url\":\"https:\\\/\\\/artmotiers.ch\\\/en\\\/retrospective\\\/exhibitions-2015\\\/\",\"name\":\"Exhibitions 2015 &#8211; Art M\u00f4tiers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/artmotiers.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/artmotiers.ch\\\/en\\\/retrospective\\\/exhibitions-2015\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/artmotiers.ch\\\/en\\\/retrospective\\\/exhibitions-2015\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/artmotiers.ch\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/motiersart_affiche_2015-scaled-e1748877053912.jpg\",\"datePublished\":\"2025-05-16T12:59:42+00:00\",\"dateModified\":\"2026-01-04T10:06:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/artmotiers.ch\\\/en\\\/retrospective\\\/exhibitions-2015\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/artmotiers.ch\\\/en\\\/retrospective\\\/exhibitions-2015\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/artmotiers.ch\\\/en\\\/retrospective\\\/exhibitions-2015\\\/#primaryimage\",\"url\":\"https:\\\/\\\/artmotiers.ch\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/motiersart_affiche_2015-scaled-e1748877053912.jpg\",\"contentUrl\":\"https:\\\/\\\/artmotiers.ch\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/motiersart_affiche_2015-scaled-e1748877053912.jpg\",\"width\":1843,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/artmotiers.ch\\\/en\\\/retrospective\\\/exhibitions-2015\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/artmotiers.ch\\\/en\\\/expo2026\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retrospective\",\"item\":\"https:\\\/\\\/artmotiers.ch\\\/en\\\/retrospective\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Exhibitions 2015\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/artmotiers.ch\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/artmotiers.ch\\\/en\\\/\",\"name\":\"Art M\u00f4tiers\",\"description\":\"Expo en plein air\",\"publisher\":{\"@id\":\"https:\\\/\\\/artmotiers.ch\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/artmotiers.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/artmotiers.ch\\\/en\\\/#organization\",\"name\":\"Art M\u00f4tiers\",\"url\":\"https:\\\/\\\/artmotiers.ch\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/artmotiers.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/artmotiers.ch\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/ART_MOTIERS_LOGO.png\",\"contentUrl\":\"https:\\\/\\\/artmotiers.ch\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/ART_MOTIERS_LOGO.png\",\"width\":6108,\"height\":3582,\"caption\":\"Art M\u00f4tiers\"},\"image\":{\"@id\":\"https:\\\/\\\/artmotiers.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exhibitions 2015 &#8211; Art M\u00f4tiers","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/artmotiers.ch\/en\/retrospective\/exhibitions-2015\/","og_locale":"en_US","og_type":"article","og_title":"Exhibitions 2015 &#8211; Art M\u00f4tiers","og_url":"https:\/\/artmotiers.ch\/en\/retrospective\/exhibitions-2015\/","og_site_name":"Art M\u00f4tiers","article_modified_time":"2026-01-04T10:06:02+00:00","og_image":[{"width":1843,"height":2560,"url":"https:\/\/artmotiers.ch\/wp-content\/uploads\/2025\/05\/motiersart_affiche_2015-scaled-e1748877053912.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/artmotiers.ch\/en\/retrospective\/exhibitions-2015\/","url":"https:\/\/artmotiers.ch\/en\/retrospective\/exhibitions-2015\/","name":"Exhibitions 2015 &#8211; Art M\u00f4tiers","isPartOf":{"@id":"https:\/\/artmotiers.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/artmotiers.ch\/en\/retrospective\/exhibitions-2015\/#primaryimage"},"image":{"@id":"https:\/\/artmotiers.ch\/en\/retrospective\/exhibitions-2015\/#primaryimage"},"thumbnailUrl":"https:\/\/artmotiers.ch\/wp-content\/uploads\/2025\/05\/motiersart_affiche_2015-scaled-e1748877053912.jpg","datePublished":"2025-05-16T12:59:42+00:00","dateModified":"2026-01-04T10:06:02+00:00","breadcrumb":{"@id":"https:\/\/artmotiers.ch\/en\/retrospective\/exhibitions-2015\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/artmotiers.ch\/en\/retrospective\/exhibitions-2015\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/artmotiers.ch\/en\/retrospective\/exhibitions-2015\/#primaryimage","url":"https:\/\/artmotiers.ch\/wp-content\/uploads\/2025\/05\/motiersart_affiche_2015-scaled-e1748877053912.jpg","contentUrl":"https:\/\/artmotiers.ch\/wp-content\/uploads\/2025\/05\/motiersart_affiche_2015-scaled-e1748877053912.jpg","width":1843,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/artmotiers.ch\/en\/retrospective\/exhibitions-2015\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/artmotiers.ch\/en\/expo2026\/"},{"@type":"ListItem","position":2,"name":"Retrospective","item":"https:\/\/artmotiers.ch\/en\/retrospective\/"},{"@type":"ListItem","position":3,"name":"Exhibitions 2015"}]},{"@type":"WebSite","@id":"https:\/\/artmotiers.ch\/en\/#website","url":"https:\/\/artmotiers.ch\/en\/","name":"Art M\u00f4tiers","description":"Expo en plein air","publisher":{"@id":"https:\/\/artmotiers.ch\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/artmotiers.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/artmotiers.ch\/en\/#organization","name":"Art M\u00f4tiers","url":"https:\/\/artmotiers.ch\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/artmotiers.ch\/en\/#\/schema\/logo\/image\/","url":"https:\/\/artmotiers.ch\/wp-content\/uploads\/2024\/10\/ART_MOTIERS_LOGO.png","contentUrl":"https:\/\/artmotiers.ch\/wp-content\/uploads\/2024\/10\/ART_MOTIERS_LOGO.png","width":6108,"height":3582,"caption":"Art M\u00f4tiers"},"image":{"@id":"https:\/\/artmotiers.ch\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/artmotiers.ch\/en\/wp-json\/wp\/v2\/pages\/33695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/artmotiers.ch\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/artmotiers.ch\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/artmotiers.ch\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/artmotiers.ch\/en\/wp-json\/wp\/v2\/comments?post=33695"}],"version-history":[{"count":2,"href":"https:\/\/artmotiers.ch\/en\/wp-json\/wp\/v2\/pages\/33695\/revisions"}],"predecessor-version":[{"id":33707,"href":"https:\/\/artmotiers.ch\/en\/wp-json\/wp\/v2\/pages\/33695\/revisions\/33707"}],"up":[{"embeddable":true,"href":"https:\/\/artmotiers.ch\/en\/wp-json\/wp\/v2\/pages\/33440"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/artmotiers.ch\/en\/wp-json\/wp\/v2\/media\/33591"}],"wp:attachment":[{"href":"https:\/\/artmotiers.ch\/en\/wp-json\/wp\/v2\/media?parent=33695"}],"wp:term":[{"taxonomy":"folder","embeddable":true,"href":"https:\/\/artmotiers.ch\/en\/wp-json\/wp\/v2\/folder?post=33695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}